{"id":10254,"date":"2012-09-12T10:51:44","date_gmt":"2012-09-12T10:51:44","guid":{"rendered":"http:\/\/www.totemguard.com\/aulatotem\/?p=10254"},"modified":"2022-03-11T11:53:09","modified_gmt":"2022-03-11T10:53:09","slug":"la-clave-del-aprendizaje-de-observador-pasivo-a-participante-activo","status":"publish","type":"post","link":"https:\/\/www.totemguard.com\/aulatotem\/2012\/09\/la-clave-del-aprendizaje-de-observador-pasivo-a-participante-activo\/","title":{"rendered":"La clave del aprendizaje: De observador pasivo a participante activo"},"content":{"rendered":"\n<blockquote class=\"wp-block-quote is-style-plain is-layout-flow wp-block-quote-is-layout-flow\"><p>El peligro de las clases magistrales es que crean la falsa sensaci\u00f3n al profesor de que ense\u00f1a y la falsa sensaci\u00f3n al alumno de que aprende<\/p><cite>&#8211; Albert Camus<\/cite><\/blockquote>\n\n\n\n<p>Sentarse pasivamente y tomar apuntes no es la mejor manera de aprender. Y sin embargo el 99% de los profesores todav\u00eda siguen este modelo de ense\u00f1ar.<\/p>\n\n\n\n<p><strong>El sistema tradicional de instrucci\u00f3n se basa en un modelo pasivo, en donde hay una simple transferencia de informaci\u00f3n del profesor al alumno<\/strong>. El alumno para aprender debe escuchar atentamente una explicaci\u00f3n m\u00e1s o menos larga y dada la complejidad de los temas tiende a distraerse, perderse o aburrirse con facilidad.<\/p>\n\n\n\n<p>En este mon\u00f3logo no hay oportunidades para que el estudiante piense de forma cr\u00edtica sobre los argumentos que se est\u00e1n presentando. Al contrario, el estudiante entiende que el objetivo de las clases es tomar apuntes para aprobar el examen y la mejor manera de hacerlo es memorizar una serie de f\u00f3rmulas, hechos y ejemplos aparentemente no interelacionados.<\/p>\n\n\n\n<p>El peligro es que cuando el alumno pasa el examen, el profesor conf\u00eda en que el alumno ha aprendido el tema y se prosigue con los siguientes cap\u00edtulos del libro de texto. Pero, en la realidad, el alumno ha memorizado simplemente datos, muchos de los cu\u00e1les olvidar\u00e1 y su cerebro no podr\u00e1 aprovechar para futuras aplicaciones en un trabajo profesional o innovar.<\/p>\n\n\n\n<p><a href=\"http:\/\/harvardmagazine.com\/2012\/03\/twilight-of-the-lecture\" target=\"_blank\" rel=\"noopener noreferrer\">Eric Mazur<\/a>, un prominente profesor de F\u00edsica de la Universidad de Harvard, ya descubri\u00f3 en los 90 que su \u00e9lite de alumnos estaban memorizando informaci\u00f3n en vez de aprender a entender la materia.<\/p>\n\n\n\n<p>De hecho, estudiantes de primer curso en Harvard no entend\u00edan conceptos tan simples como la segunda Ley de Newton. Los alumnos resolv\u00edan f\u00e1cilmente problemas de f\u00edsica que se hab\u00edan realizado en clase. Pero, para su sorpresa, si el mismo concepto lo preguntaba de forma diferente, con un problema conceptual que nunca hab\u00edan visto antes, estos mismos alumnos eran incapaces de ver los elementos en com\u00fan con el problema que s\u00ed sab\u00edan resolver.<\/p>\n\n\n\n<p>Como ser humano, primero pens\u00f3 que la culpa la ten\u00edan los alumnos o el libro de texto o incluso el examen. Pero tras realizar serios estudios y pruebas lleg\u00f3 a la dolorosa conclusi\u00f3n de que su forma de ense\u00f1ar era la causa que hac\u00eda que sus alumnos fallaran.<\/p>\n\n\n\n<p>Eric Mazur cambi\u00f3 el enfoque en sus clases y desarroll\u00f3 un programa interactivo para el aula llamado \u00ab<a href=\"https:\/\/mazur.harvard.edu\/research-areas\/peer-instruction\" target=\"_blank\" rel=\"noreferrer noopener\">Peer Instruction<\/a>\u00ab<strong>,&nbsp;<\/strong>mejorando el rendimiento de los estudiantes de forma significativa.<\/p>\n\n\n\n<p>Del mismo modo, <a href=\"http:\/\/en.wikipedia.org\/wiki\/David_Hestenes\" target=\"_blank\" rel=\"noopener noreferrer\">David Hestenes<\/a>, un profesor de la Arizona State University, vio la gran disparidad entre lo que realmente aprend\u00eda el alumno en las asignaturas de F\u00edsica, Matem\u00e1ticas, Ciencias o &nbsp;Ingenier\u00eda en la escuela y en la universidad, en comparaci\u00f3n con las habilidades que necesitaba un cient\u00edfico o matem\u00e1tico en la vida real. Es cierto que raramente te encuentras con un problema para el que existe la f\u00f3rmula exacta y todos los datos disponibles para calcular el resultado.<\/p>\n\n\n\n<p>David Hestenes&nbsp;decidi\u00f3<strong> dejar de confiar el aprendizaje alrededor de los libros de texto y las clases magistrales<\/strong>, para crear un m\u00e9todo interactivo en donde <strong>el alumno pasa de ser un observador pasivo a un participante activo.<\/strong><\/p>\n\n\n\n<p>Su m\u00e9todo llamado \u00ab<strong>Modeling Instruction<\/strong>\u00bb llama especialmente la atenci\u00f3n por su gran efectividad durante los \u00faltimos a\u00f1os en los EEUU tras ser adoptado por importantes centros educativos y universidades. El programa va dirigido especialmente al aprendizaje de las Ciencias, Tecnolog\u00eda, Ingenier\u00eda y Matem\u00e1ticas. Su clave de \u00e9xito es que los alumnos participan activamente en crear y dise\u00f1ar sus propios experimentos y averiguan por s\u00ed mismos c\u00f3mo funciona el mundo f\u00edsico que les rodea.<\/p>\n\n\n\n<p>Imaginemos que queremos que los estudiantes comprendan el siguiente tema:<\/p>\n\n\n\n<p><strong>Principio f\u00edsico:<\/strong> Segunda Ley de Newton<\/p>\n\n\n\n<p><strong>Objetivo del modelo<\/strong>: Representar el movimiento de un objeto material sometido a una fuerza constante<\/p>\n\n\n\n<p>En vez de explicar el principio te\u00f3rico de la Ley de Newton, escribir las f\u00f3rmulas y despu\u00e9s ir al laboratorio para realizar experimentos, <strong>en el \u00abModeling instruction\u00bb el orden se invierte.<\/strong>&nbsp;El alumno no usa el laboratorio para autentificar la explicaci\u00f3n del profesor sino que el alumno construye su propia autoridad.&nbsp;<strong>Se definen dos etapas<\/strong>:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span style=\"font-weight: bold; color: rgb(0, 0, 128);\">1. El profesor presenta un escenario real y los alumnos desarrollan el modelo&nbsp;<\/span><\/h3>\n\n\n\n<p>El profesor motiva al estudiante con un escenario simple de su entorno para que lo pueda comprender, por ejemplo, un coche el\u00e9ctrico que se mueve a una velocidad constante.<\/p>\n\n\n\n<p><strong>Al contrario del modelo tradicional, no se presenta previamente ning\u00fan conocimiento te\u00f3rico del principio que se desea que aprendan<\/strong>. El primer paso es ir al laboratorio y realizar experimentos que nos permitan desarrollar un modelo matem\u00e1tico que explique lo que est\u00e1 pasando.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li> <strong style=\"color: revert; font-size: revert; font-family: -apple-system, BlinkMacSystemFont, &quot;Segoe UI&quot;, Roboto, Oxygen-Sans, Ubuntu, Cantarell, &quot;Helvetica Neue&quot;, sans-serif;\">Los alumnos colaboran en grupos<\/strong> <\/li><\/ul>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.totemguard.com\/aulatotem\/wp-content\/uploads\/2012\/09\/whiteboard_usa-300x225.jpg\" alt=\"\" class=\"wp-image-10425\" srcset=\"https:\/\/www.totemguard.com\/aulatotem\/wp-content\/uploads\/2012\/09\/whiteboard_usa-300x225.jpg 300w, https:\/\/www.totemguard.com\/aulatotem\/wp-content\/uploads\/2012\/09\/whiteboard_usa.jpg 450w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption>Foto: whiteboardsusa.com<\/figcaption><\/figure><\/div>\n\n\n\n<p>Los alumnos colaboran en grupos y entran a razonar que est\u00e1n observando, qu\u00e9 variables intervienen, qu\u00e9 podemos medir, qu\u00e9 podemos cambiar, etc. El profesor mantiene discretamente el control de &nbsp;la agenda pero sin obstruir la discusi\u00f3n que sucede entre los alumnos, ni actuar como una autoridad o una fuente de conocimiento.<\/p>\n\n\n\n<p>Los alumnos a continuaci\u00f3n dise\u00f1an su experimento alrededor de las preguntas que han surgido. Deben decidir qu\u00e9 cantidad de datos van registrar, c\u00f3mo los van a registrar, c\u00f3mo los van a analizar. No hay un proceso establecido o una receta m\u00e1gica que deben seguir.<\/p>\n\n\n\n<p>Normalmente recopilan y analizan datos en un ordenador y empiezan a formular la relaci\u00f3n funcional entre las variables que intervienen en el funcionamiento del coche el\u00e9ctrico.<\/p>\n\n\n\n<p>El objetivo principal de la actividad en el laboratorio es que<strong> los estudiantes aprendan a relacionar de forma conceptual los fen\u00f3menos que ocurren en el mundo real con unas representaciones simb\u00f3licas<\/strong>.<\/p>\n\n\n\n<p>El gran beneficio de este sistema es que cada grupo discute los resultados del problema e intenta llegar a un acuerdo sobre la respuesta correcta, con lo que hay una gran cantidad de razonamiento y aprendizaje. &nbsp;Las representaciones simb\u00f3licas y los datos registrados, se deben plasmar en una simple pizarra blanca.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li> <strong style=\"color: revert; font-size: revert; font-family: -apple-system, BlinkMacSystemFont, &quot;Segoe UI&quot;, Roboto, Oxygen-Sans, Ubuntu, Cantarell, &quot;Helvetica Neue&quot;, sans-serif;\">Los alumnos presentan el resultado de sus experimentos<\/strong><\/li><\/ul>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.totemguard.com\/aulatotem\/wp-content\/uploads\/2012\/09\/CIMM09_Photo-ChrisHorton-300x225.jpg\" alt=\"\" class=\"wp-image-10423\" title=\"CIMM09_Photo-ChrisHorton\" srcset=\"https:\/\/www.totemguard.com\/aulatotem\/wp-content\/uploads\/2012\/09\/CIMM09_Photo-ChrisHorton-300x225.jpg 300w, https:\/\/www.totemguard.com\/aulatotem\/wp-content\/uploads\/2012\/09\/CIMM09_Photo-ChrisHorton.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure><\/div>\n\n\n\n<p>Tras la fase de experimentaci\u00f3n, cada grupo comparte y presenta los resultados de los experimentos con la clase mostrando su pizarra blanca, como si se tratara de una comunidad cient\u00edfica. Como punto diferencial de este sistema se pide siempre elaborar m\u00faltiples representaciones de los datos registrados: gr\u00e1ficos, diagramas, tablas, \u00e1lgebra, etc. Con estas representaciones los alumnos ven el mismo concepto desde diferentes \u00e1ngulos, expandiendo la manera de pensar de sus cerebros y aprendiendo de forma m\u00e1s profunda.<\/p>\n\n\n\n<p>Durante estas presentaciones, el profesor hace preguntas: \u00bfPor qu\u00e9 has hecho esto? \u00bfC\u00f3mo sabes esto? La clase tambi\u00e9n se suma a la interrogaci\u00f3n. <strong>Cada grupo, por su parte, ha de justificar sus conclusiones y a partir de aqu\u00ed se inicia un debate sobre los resultados que han obtenido los diferentes grupos<\/strong>.<\/p>\n\n\n\n<p>Al final se llega a un consenso como comunidad para definir c\u00f3mo funciona el modelo y el principio que est\u00e1n estudiando.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span style=\"color: #000080;\"><strong>2. El profesor var\u00eda el escenario original y los alumnos predicen los nuevos resultados<\/strong><\/span><\/h3>\n\n\n\n<p>Tras haber descubierto el principio que explica el escenario original, se resuelven algunos ejercicios te\u00f3ricos, t\u00edpicos del libro de texto, para afianzar los conocimientos.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>\n<h4><strong>Los alumnos vuelven al laboratorio<\/strong><\/h4>\n<\/li><\/ul>\n\n\n\n<p>El profesor introduce una serie de nuevas situaciones f\u00edsicas. La introducci\u00f3n de nuevas variables ayudan al estudiante a entender el modelo m\u00e1s all\u00e1 del contexto espec\u00edfico en que se desarroll\u00f3. En el ejemplo del coche el\u00e9ctrico podemos preguntar \u00bfqu\u00e9 ocurre si la velocidad no es constante?, \u00bfqu\u00e9 sucede si empujamos el coche por detr\u00e1s? Seg\u00fan lo aprendido \u00bfdir\u00edas que los coches que circulan por la carretera delante del colegio van demasiado deprisa? etc.<\/p>\n\n\n\n<p>Los alumnos vuelven al laboratorio o cuando sea posible montan el experimento fuera del aula: empujamos un coche real y registramos nuevos datos, observamos y grabamos en video los coches que circulan por la carretera, etc.<strong>&nbsp;Se busca siempre la ciencia alrededor del centro para que el alumno pueda explorar, modificar y aplicar el modelo a un nuevo escenario concreto<\/strong>.&nbsp;Tras las observaciones, el modelo se modifica para describir, explicar o dise\u00f1ar el nuevo experimento propuesto.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li> <strong style=\"color: revert; font-size: revert; font-family: -apple-system, BlinkMacSystemFont, &quot;Segoe UI&quot;, Roboto, Oxygen-Sans, Ubuntu, Cantarell, &quot;Helvetica Neue&quot;, sans-serif;\">Los alumnos predicen los resultados<\/strong><span style=\"color: revert; font-size: revert; font-weight: revert; font-family: -apple-system, BlinkMacSystemFont, &quot;Segoe UI&quot;, Roboto, Oxygen-Sans, Ubuntu, Cantarell, &quot;Helvetica Neue&quot;, sans-serif;\"> <\/span><\/li><\/ul>\n\n\n\n<p>Un ejercicio adicional del programa es hacer que los alumnos hagan predicciones sobre lo que va ocurrir en un experimento. Las predicciones les ayudan a afianzar conceptos y a entender el porqu\u00e9 de sus errores de una forma visual. Por ejemplo, se les hace predecir el punto exacto en donde dos coches que circulan a distintas velocidades chocar\u00e1n y explicar porqu\u00e9 ocurrir\u00e1 aqu\u00ed.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span style=\"color: #000080;\"><strong>\u00bfQu\u00e9 beneficios reportan los profesores que aplican este modelo en el aula?&nbsp;<\/strong><\/span><\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li>El alumno siente que aprende con un prop\u00f3sito claro. Resuelve problemas reales de su entorno y <strong>est\u00e1 m\u00e1s motivado a poner el esfuerzo intelectual<\/strong> que requiere el estudio de estas materias.<\/li><li>El alumno <strong>deja de memorizar f\u00f3rmulas matem\u00e1ticas<\/strong> <strong>para aprender a razonar de forma l\u00f3gica<\/strong>.&nbsp;El alumno sabe que una respuesta num\u00e9rica no es suficiente. Debe esforzarse y construir un modelo para comprender el problema. Ha de experimentar con su grupo en el laboratorio, debe justificar su respuesta en frente de sus otros compa\u00f1eros y adem\u00e1s ha de ser capaz de predecir otros escenarios similares.<\/li><li><strong>Mejora el grado de retenci\u00f3n de conceptos complejos<\/strong>. Los alumnos que argumentan y explican activamente conceptos cient\u00edficos, son capaces de recordar la informaci\u00f3n al largo plazo.<\/li><li>Las matem\u00e1ticas, la f\u00edsica o la biolog\u00eda se contextualizan con escenarios cercanos al alumno, que de entrada ya puede entender, sentirse menos intimidado y a largo plazo<strong> generar mas cient\u00edficos.<\/strong><\/li><li>El alumno empieza a formularse a diario preguntas interesantes y a <strong>reconocer la ciencia en todo los que le rodea<\/strong> (deporte, hechos reales, cine, econom\u00eda, arte, etc.) y aporta nuevos retos al aula, que a su vez despierta la curiosidad y el debate de sus compa\u00f1eros.<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><span style=\"color: #000080;\"><strong>\u00bfQu\u00e9 dificultades presenta para el profesor un modelo interactivo?<\/strong><\/span><\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>El ritmo de la clase para el profesor puede ser duro<\/strong>.&nbsp;Cuando el profesor simplemente transfiere informaci\u00f3n al alumno en el aula, el profesor puede poner el piloto autom\u00e1tico. En el caso de \u00abun programa interactivo\u00bb, cada clase es diferente.&nbsp;En ocasiones hay que improvisar, los alumnos experimentan en direcciones diferentes, tienen diferencias personales entre ellos y no es f\u00e1cil seguir lo que est\u00e1 haciendo cada grupo para asegurar que se cubren los puntos m\u00e1s importantes. <strong>En este aparente caos, sin embargo, es donde el mayor aprendizaje tiene lugar.<\/strong><\/li><li>Con un modelo interactivo es <strong>dif\u00edcil cubrir t<\/strong><strong>odo el material curricular<\/strong> que viene impuesto al profesor.<\/li><li>El profesor es un facilitador del aprendizaje y no una fuente de conocimiento y por tanto debe desarrollar buenas pr\u00e1cticas de interrogatorio al estilo del <a href=\"http:\/\/es.wikipedia.org\/wiki\/M%C3%A9todo_socr%C3%A1tico\" target=\"_blank\" rel=\"noopener noreferrer\">m\u00e9todo Socr\u00e1tico<\/a>. <strong>Se hace dif\u00edcil para el profesor no intervenir y corregir un concepto err\u00f3neo<\/strong> a partir del cual van a construir un modelo. Sin embargo, lo que ocurre con frecuencia si se tiene paciencia, es que los alumnos corrigen sus propios errores cuando elaboran sus presentaciones en la pizarra blanca. No es extra\u00f1o ver cinco soluciones diferentes al mismo problema, todas ellas correctas. La diversidad de pensamiento surge constantemente.<\/li><li><strong>El alumno tambi\u00e9n a veces se resiste a este nuevo modelo<\/strong>. La queja principal en la universidad es que han de aprender por ellos mismos, cuando simplemente desean aprobar el examen para obtener el t\u00edtulo. &nbsp;Muchos prefieren escuchar y tomar apuntes ya que tampoco son conscientes de que un sistema pasivo no les prepara para resolver los problemas desconocidos con los que se encontrar\u00e1n en su vida profesional.<\/li><li><strong>Este tipo de modelo requiere tambi\u00e9n un cambio en el modelo de evaluaci\u00f3n que se hace al alumno<\/strong>. Se intenta realizar un m\u00ednimo de ex\u00e1menes para cumplir con los requisitos legales. Las pruebas se basan m\u00e1s en el razonamiento cient\u00edfico y en el dise\u00f1o de un experimento, en vez de enfocarlo en la repetici\u00f3n del contenido de un libro de texto.<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><span style=\"color: #000080;\">\u00bfQu\u00e9 papel tiene la tecnolog\u00eda dentro del aula en este modelo de instrucci\u00f3n?<\/span><\/h3>\n\n\n\n<p>B\u00e1sicamente la tecnolog\u00eda en el aula se utiliza para<strong> permitir la exploraci\u00f3n en vez de simplemente dispensar informaci\u00f3n cient\u00edfica:<\/strong><\/p>\n\n\n\n<p>1) La tecnolog\u00eda hace m\u00e1s f\u00e1cil presentar un escenario real a los alumnos, el cual ser\u00eda dif\u00edcil de reproducir en el aula. Por ejemplo, un video en YouTube de un coche saltando por una rampa, una toma en Google Earth o introducir un juego como MineCraft para cuestionarnos principios f\u00edsicos.<\/p>\n\n\n\n<p>2) La tecnolog\u00eda permite a los alumnos grabar videos para observar y registrar datos y realizar c\u00e1lculos num\u00e9ricos. Tambi\u00e9n permite documentar a posteriori los experimentos realizados y los conceptos aprendidos v\u00eda blogs, sitios webs y presentaciones y compartirlos con otros centros y docentes.<\/p>\n\n\n\n<p><span style=\"color: #000080;\"><strong>Algunos recursos a consultar y aprovechar para tus clases:<\/strong><\/span><\/p>\n\n\n\n<p>Para conocer m\u00e1s a fondo este modelo de aprendizaje, puedes leer el libro \u00ab<a href=\"https:\/\/amzn.to\/3t4sT2Z\" target=\"_blank\" rel=\"noreferrer noopener\">Tutor\u00eda Entre Iguales: De La Teor\u00eda A La Pr\u00e1ctica: Un m\u00e9todo de aprendizaje cooperativo para la diversidad en secundaria<\/a>\u00bb <\/p>\n\n\n\n<p>Tambi\u00e9n numerosos profesores publican contenido gratuito y videos para usar en el aula que invitan al razonamiento y no a la simple memorizaci\u00f3n de conceptos:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"http:\/\/blog.mrmeyer.com\/?cat=83\" target=\"_blank\" rel=\"noopener noreferrer\">Escenarios matem\u00e1ticos por Dan Meyer<\/a><\/li><li><a href=\"http:\/\/fnoschese.wordpress.com\/modeling-instruction\/\" target=\"_blank\" rel=\"noopener noreferrer\">Frank Noschese y el Modelling Instruction<\/a><\/li><li><a href=\"http:\/\/physicsmistakes.wordpress.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Errores en f\u00edsica<\/a><\/li><li><a href=\"https:\/\/amzn.to\/3KFelg9\" target=\"_blank\" rel=\"noreferrer noopener\">Peer instruction: Manual de Instrucci\u00f3n por Eric Mazur<\/a><\/li><li><a href=\"http:\/\/puntmat.blogspot.com.es\/\" target=\"_blank\" rel=\"noopener noreferrer\">PuntMat<\/a><\/li><\/ul>\n\n\n\n<p>Incorporar un modelo interactivo en el aula puede parecer dif\u00edcil pero podemos cambiar ciertos aspectos para un aprendizaje m\u00e1s interactivo.<\/p>\n\n\n\n<p>Preg\u00fantate \u00bfestoy hablando yo todo el rato? Si hago una pregunta y la respuesta es incorrecta, \u00bfles corrijo de inmediato? \u00bfDescubren los errores por s\u00ed solos? \u00bfHago preguntas que generan debate? \u00bfPuedo hacerles razonar m\u00e1s en grupo para que aprendan unos de otros y &nbsp;se aproveche la diversidad de capacidades?<\/p>\n\n\n\n<p class=\"has-background\" style=\"background-color:#eff1f2\">\u00bfUtilizas ya el aprendizaje entre iguales o un modelo interactivo? D\u00e9jame tu experiencia en comentarios para poder todos aprender.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\r\n\t\t<div id=\"cp_popup_id_21735\" class=\"cp-popup-container cp-popup-live-wrap cp_style_21735 cp-module-inline cpro-open \" data-style=\"cp_style_21735\" data-module-type=\"inline\" data-class-id=\"21735\" data-styleslug=\"tablet-ebook-banner-in-form-2\">\r\n\r\n\t\t\t\r\n\t\t\t<div class=\"cp-popup-wrapper cp-manual cp-popup-inline  \"  >\r\n\t\t\t\t<div class=\"cp-popup  cpro-animate-container \">\r\n\r\n\t\t\t\t\t\r\n\t\t\t\t<input type='hidden' class='panel-settings' data-style_id= '21735' data-section='configure' value='{&quot;0&quot;:{&quot;target_geo_rule_exclude_on_specifics-geo_0&quot;:[&quot;BO&quot;,&quot;PY&quot;,&quot;VE&quot;]},&quot;show_for_logged_in&quot;:&quot;1&quot;,&quot;hide_on_device&quot;:&quot;mobile&quot;,&quot;cp_hide_on_device&quot;:&quot;mobile&quot;}' ><input type='hidden' class='panel-rulesets' data-style_id= '21735' data-section='configure' value='[]' ><style id='cp_popup_style_21735' type='text\/css'>.cp_style_21735 .cp-popup-content {font-family:Work Sans;font-style:Normal;font-weight:Normal;}.cp_style_21735 .cp-popup-content{ border-style:solid;border-color:#cccccc;border-width:2px 2px 2px 2px;border-radius:2px 2px 2px 2px;mobile-breakpoint:767;}.cp_style_21735 #panel-1-21735 .cp-target:hover { }.cp_style_21735 #panel-1-21735 { }.cp_style_21735 .cp-popup-content { background : #3c5c75;background : -webkit-linear-gradient(180deg, #3c5c75 0%, #ddd  100%);background : -moz-linear-gradient(180deg, #3c5c75 0%, #ddd  100%);background : -ms-linear-gradient(180deg, #3c5c75 0%, #ddd  100%);background : -o-linear-gradient(180deg, #3c5c75 0%, #ddd  100%);background : linear-gradient(180deg, #3c5c75 0%, #ddd  100%);width:700px;height:245px;}@media ( max-width: 767px ) {.cp_style_21735 .cp-popup-content{ border-style:solid;border-color:#cccccc;border-width:2px 2px 2px 2px;border-radius:2px 2px 2px 2px;mobile-breakpoint:767;}.cp_style_21735 #panel-1-21735 .cp-target:hover { }.cp_style_21735 #panel-1-21735 { }.cp_style_21735 .cp-popup-content { background-color:#fff;width:320px;height:240px;}}.cp_style_21735 .cp-popup .cpro-form .cp-form-input-field{ font-family:Lato;font-style:Inherit;font-weight:Inherit;font-size:14px;letter-spacing:0px;text-align:left;color:#8e8e8e;background-color:#fff;border-style:solid;border-width:1px 1px 1px 1px;border-radius:30px 0px 0px 30px;border-color:#bbb;active-border-color:#666;padding:0px 12px 0px 21px;text-transform:none;}.cp_style_21735 #form_field-21735 .cp-target:hover { }.cp_style_21735 #form_field-21735 placeholder { color:#8e8e8e;}.cp_style_21735 .cp-popup .cpro-form .cp-form-input-field input[type='radio'], .cp_style_21735 .cp-popup .cpro-form .cp-form-input-field input[type='checkbox'] {color:#8e8e8e;background-color:#fff;}.cp_style_21735 .cp-popup .cpro-form .cp-form-input-field:focus {border-color: #666;}.cp_style_21735 .cp-popup .cpro-form .cp-form-input-field::-webkit-input-placeholder {color:#8e8e8e;}.cp_style_21735 .cp-popup .cpro-form .cp-form-input-field::-moz-placeholder  {color:#8e8e8e;}.cp_style_21735 .cp-popup .cpro-form .pika-lendar table tbody button:hover { background :#8e8e8e;}.cp_style_21735 .cp-popup .cpro-form .pika-lendar table tbody .is-selected .pika-button { background :#8e8e8e;box-shadow : inset 0 1px 3px #8e8e8e;}.cp_style_21735 #form_field-21735 { }@media ( max-width: 767px ) {.cp_style_21735 .cp-popup .cpro-form .cp-form-input-field{ font-family:Lato;font-style:Inherit;font-weight:Inherit;font-size:12px;letter-spacing:0px;text-align:left;color:#8e8e8e;background-color:#fff;border-style:solid;border-width:1px 1px 1px 1px;border-radius:30px 0px 0px 30px;border-color:#bbb;active-border-color:#666;padding:0px 12px 0px 21px;text-transform:none;}.cp_style_21735 #form_field-21735 .cp-target:hover { }.cp_style_21735 #form_field-21735 placeholder { color:#8e8e8e;}.cp_style_21735 .cp-popup .cpro-form .cp-form-input-field input[type='radio'], .cp_style_21735 .cp-popup .cpro-form .cp-form-input-field input[type='checkbox'] {color:#8e8e8e;background-color:#fff;}.cp_style_21735 .cp-popup .cpro-form .cp-form-input-field:focus {border-color: #666;}.cp_style_21735 .cp-popup .cpro-form .cp-form-input-field::-webkit-input-placeholder {color:#8e8e8e;}.cp_style_21735 .cp-popup .cpro-form .cp-form-input-field::-moz-placeholder  {color:#8e8e8e;}.cp_style_21735 .cp-popup .cpro-form .pika-lendar table tbody button:hover { background :#8e8e8e;}.cp_style_21735 .cp-popup .cpro-form .pika-lendar table tbody .is-selected .pika-button { background :#8e8e8e;box-shadow : inset 0 1px 3px #8e8e8e;}.cp_style_21735 #form_field-21735 { }}.cp_style_21735 #cp_heading-1-21735 .cp-target { font-family:Newsreader;font-style:Inherit;font-weight:Inherit;font-size:31px;line-height:1;letter-spacing:0px;text-align:center;color:#ffffff;width:347px;height:64px;}.cp_style_21735 #cp_heading-1-21735 .cp-target:hover { }.cp_style_21735 #cp_heading-1-21735 .cp-rotate-wrap{ transform:rotate( 0deg);}.cp_style_21735 #cp_heading-1-21735 { left: 320px;top: 64.5px;z-index:10;}@media ( max-width: 767px ) {.cp_style_21735 #cp_heading-1-21735 .cp-target { font-family:Newsreader;font-style:Inherit;font-weight:Inherit;font-size:23px;line-height:1.08;letter-spacing:0.06;text-align:center;color:#ffffff;width:301px;height:34px;}.cp_style_21735 #cp_heading-1-21735 .cp-target:hover { }.cp_style_21735 #cp_heading-1-21735 .cp-rotate-wrap{ transform:rotate( 0deg);}.cp_style_21735 #cp_heading-1-21735 { left: 8.5px;top: 64px;z-index:10;}}.cp_style_21735 #cp_heading-3-21735 .cp-target { font-family:Inter;font-style:Inherit;font-weight:Inherit;font-size:18px;line-height:1.05;letter-spacing:1px;text-align:center;color:#ffffff;width:384px;height:19px;}.cp_style_21735 #cp_heading-3-21735 .cp-target:hover { }.cp_style_21735 #cp_heading-3-21735 .cp-rotate-wrap{ transform:rotate( 0deg);}.cp_style_21735 #cp_heading-3-21735 { left: 301.5px;top: 18.5px;z-index:14;}@media ( max-width: 767px ) {.cp_style_21735 #cp_heading-3-21735 .cp-target { font-family:Inter;font-style:Inherit;font-weight:Inherit;font-size:17px;line-height:1.05;letter-spacing:1px;text-align:left;color:#ffffff;width:126px;height:19px;}.cp_style_21735 #cp_heading-3-21735 .cp-target:hover { }.cp_style_21735 #cp_heading-3-21735 .cp-rotate-wrap{ transform:rotate( 0deg);}.cp_style_21735 #cp_heading-3-21735 { left: 115px;top: 25px;z-index:14;}}.cp_style_21735 #cp_shape-4-21735 .cp-target { width:25px;height:25px;}.cp_style_21735 #cp_shape-4-21735 .cp-target:hover { }.cp_style_21735 #cp_shape-4-21735 .cp-target { fill:#f77b55;}.cp_style_21735 #cp_shape-4-21735 .cp-target .cp-shape-first-color { fill:#f77b55;}.cp_style_21735 #cp_shape-4-21735 .cp-target { }.cp_style_21735 #cp_shape-4-21735 .cp-target ~ .cp-field-shadow { }.cp_style_21735 #cp_shape-4-21735 { }.cp_style_21735 #cp_shape-4-21735 .cp-rotate-wrap{ transform:rotate( 0deg);}.cp_style_21735 #cp_shape-4-21735 { }.cp_style_21735 #cp_shape-4-21735 .cp-target:hover { }.cp_style_21735 #cp_shape-4-21735 .cp-target:hover .cp-shape-first-color { }.cp_style_21735 #cp_shape-4-21735 { left: 163.5px;top: 37.5px;z-index:16;}@media ( max-width: 767px ) {.cp_style_21735 #cp_shape-4-21735 .cp-target { width:25px;height:25px;}.cp_style_21735 #cp_shape-4-21735 .cp-target:hover { }.cp_style_21735 #cp_shape-4-21735 .cp-target { fill:#f77b55;}.cp_style_21735 #cp_shape-4-21735 .cp-target .cp-shape-first-color { fill:#f77b55;}.cp_style_21735 #cp_shape-4-21735 .cp-target { }.cp_style_21735 #cp_shape-4-21735 .cp-target ~ .cp-field-shadow { }.cp_style_21735 #cp_shape-4-21735 { }.cp_style_21735 #cp_shape-4-21735 .cp-rotate-wrap{ transform:rotate( 0deg);}.cp_style_21735 #cp_shape-4-21735 { }.cp_style_21735 #cp_shape-4-21735 .cp-target:hover { }.cp_style_21735 #cp_shape-4-21735 .cp-target:hover .cp-shape-first-color { }.cp_style_21735 #cp_shape-4-21735 { left: 82.5px;top: 18.5px;z-index:16;}}.cp_style_21735 #cp_button-4-21735 .cp-target { font-family:Inter;font-style:Inherit;font-weight:Inherit;font-size:18px;letter-spacing:0px;text-align:center;color:#443d2c;background:#ecedb6;width:260px;height:50px;padding:0px 15px 0px 15px;}.cp_style_21735 #cp_button-4-21735 .cp-target:hover { color:#fff;background:#c9bc32;}.cp_style_21735 #cp_button-4-21735 .cp-target { border-style:solid;}.cp_style_21735 #cp_button-4-21735 .cp-target ~ .cp-field-shadow { border-style:solid;}.cp_style_21735 #cp_button-4-21735 .cp-target { border-color:#443d2c;}.cp_style_21735 #cp_button-4-21735 .cp-target ~ .cp-field-shadow { border-color:#443d2c;}.cp_style_21735 #cp_button-4-21735 .cp-target { border-width:1px 1px 1px 1px;}.cp_style_21735 #cp_button-4-21735 .cp-target ~ .cp-field-shadow { border-width:1px 1px 1px 1px;}.cp_style_21735 #cp_button-4-21735 .cp-target { border-radius:20px 20px 20px 20px;}.cp_style_21735 #cp_button-4-21735 .cp-target ~ .cp-field-shadow { border-radius:20px 20px 20px 20px;}.cp_style_21735 #cp_button-4-21735 .cp-target > .cp-close-link { border-radius:20px 20px 20px 20px;}.cp_style_21735 #cp_button-4-21735 .cp-target > .cp-close-image { border-radius:20px 20px 20px 20px;}.cp_style_21735 #cp_button-4-21735 .cp-target { -webkit-box-shadow:0px 0px 5px 1px rgba(86,86,131,0.6);-moz-box-shadow:0px 0px 5px 1px rgba(86,86,131,0.6);box-shadow:0px 0px 5px 1px rgba(86,86,131,0.6);}.cp_style_21735 #cp_button-4-21735 .cp-target ~ .cp-field-shadow { -webkit-box-shadow:0px 0px 5px 1px rgba(86,86,131,0.6);-moz-box-shadow:0px 0px 5px 1px rgba(86,86,131,0.6);box-shadow:0px 0px 5px 1px rgba(86,86,131,0.6);}.cp_style_21735 #cp_button-4-21735 .cp-rotate-wrap{ transform:rotate( 0deg);}.cp_style_21735 #cp_button-4-21735 .cp-target:hover { }.cp_style_21735 #cp_button-4-21735 .cp-target:hover ~ .cp-field-shadow { }.cp_style_21735 #cp_button-4-21735 { left: 363.5px;top: 170px;z-index:22;}@media ( max-width: 767px ) {.cp_style_21735 #cp_button-4-21735 .cp-target { font-family:Inter;font-style:Inherit;font-weight:Inherit;font-size:10px;letter-spacing:0px;text-align:center;color:#443d2c;background:#ecedb6;width:130px;height:25px;padding:0px 15px 0px 15px;}.cp_style_21735 #cp_button-4-21735 .cp-target:hover { color:#fff;background:#c9bc32;}.cp_style_21735 #cp_button-4-21735 .cp-target { border-style:solid;}.cp_style_21735 #cp_button-4-21735 .cp-target ~ .cp-field-shadow { border-style:solid;}.cp_style_21735 #cp_button-4-21735 .cp-target { border-color:#443d2c;}.cp_style_21735 #cp_button-4-21735 .cp-target ~ .cp-field-shadow { border-color:#443d2c;}.cp_style_21735 #cp_button-4-21735 .cp-target { border-width:1px 1px 1px 1px;}.cp_style_21735 #cp_button-4-21735 .cp-target ~ .cp-field-shadow { border-width:1px 1px 1px 1px;}.cp_style_21735 #cp_button-4-21735 .cp-target { border-radius:20px 20px 20px 20px;}.cp_style_21735 #cp_button-4-21735 .cp-target ~ .cp-field-shadow { border-radius:20px 20px 20px 20px;}.cp_style_21735 #cp_button-4-21735 .cp-target > .cp-close-link { border-radius:20px 20px 20px 20px;}.cp_style_21735 #cp_button-4-21735 .cp-target > .cp-close-image { border-radius:20px 20px 20px 20px;}.cp_style_21735 #cp_button-4-21735 .cp-target { -webkit-box-shadow:0px 0px 5px 1px rgba(86,86,131,0.6);-moz-box-shadow:0px 0px 5px 1px rgba(86,86,131,0.6);box-shadow:0px 0px 5px 1px rgba(86,86,131,0.6);}.cp_style_21735 #cp_button-4-21735 .cp-target ~ .cp-field-shadow { -webkit-box-shadow:0px 0px 5px 1px rgba(86,86,131,0.6);-moz-box-shadow:0px 0px 5px 1px rgba(86,86,131,0.6);box-shadow:0px 0px 5px 1px rgba(86,86,131,0.6);}.cp_style_21735 #cp_button-4-21735 .cp-rotate-wrap{ transform:rotate( 0deg);}.cp_style_21735 #cp_button-4-21735 .cp-target:hover { }.cp_style_21735 #cp_button-4-21735 .cp-target:hover ~ .cp-field-shadow { }.cp_style_21735 #cp_button-4-21735 { left: 164px;top: 84px;z-index:22;}}.cp_style_21735 #cp_shape-6-21735 .cp-target { fill:#cccccc;stroke-width:2;width:200px;height:2px;}.cp_style_21735 #cp_shape-6-21735 .cp-target:hover { }.cp_style_21735 #cp_shape-6-21735 .cp-target { }.cp_style_21735 #cp_shape-6-21735 .cp-target ~ .cp-field-shadow { }.cp_style_21735 #cp_shape-6-21735 { }.cp_style_21735 #cp_shape-6-21735 .cp-rotate-wrap{ transform:rotate( 0deg);}.cp_style_21735 #cp_shape-6-21735 { }.cp_style_21735 #cp_shape-6-21735 { left: 398px;top: 48.5px;z-index:23;}@media ( max-width: 767px ) {.cp_style_21735 #cp_shape-6-21735 .cp-target { fill:#cccccc;stroke-width:2;width:98px;height:2px;}.cp_style_21735 #cp_shape-6-21735 .cp-target:hover { }.cp_style_21735 #cp_shape-6-21735 .cp-target { }.cp_style_21735 #cp_shape-6-21735 .cp-target ~ .cp-field-shadow { }.cp_style_21735 #cp_shape-6-21735 { }.cp_style_21735 #cp_shape-6-21735 .cp-rotate-wrap{ transform:rotate( 0deg);}.cp_style_21735 #cp_shape-6-21735 { }.cp_style_21735 #cp_shape-6-21735 { left: 176px;top: 26px;z-index:23;}}.cp_style_21735 #cp_image-4-21735 .cp-target { width:367px;height:265px;}.cp_style_21735 #cp_image-4-21735 .cp-target:hover { }.cp_style_21735 #cp_image-4-21735 .cp-target { border-style:none;}.cp_style_21735 #cp_image-4-21735 .cp-target ~ .cp-field-shadow { border-style:none;}.cp_style_21735 #cp_image-4-21735 .cp-target { border-color:#757575;}.cp_style_21735 #cp_image-4-21735 .cp-target ~ .cp-field-shadow { border-color:#757575;}.cp_style_21735 #cp_image-4-21735 .cp-target { border-width:1px 1px 1px 1px;}.cp_style_21735 #cp_image-4-21735 .cp-target ~ .cp-field-shadow { border-width:1px 1px 1px 1px;}.cp_style_21735 #cp_image-4-21735 .cp-target { border-radius:0px 0px 0px 0px;}.cp_style_21735 #cp_image-4-21735 .cp-target ~ .cp-field-shadow { border-radius:0px 0px 0px 0px;}.cp_style_21735 #cp_image-4-21735 .cp-target > .cp-close-link { border-radius:0px 0px 0px 0px;}.cp_style_21735 #cp_image-4-21735 .cp-target > .cp-close-image { border-radius:0px 0px 0px 0px;}.cp_style_21735 #cp_image-4-21735 .cp-target { }.cp_style_21735 #cp_image-4-21735 .cp-target ~ .cp-field-shadow { }.cp_style_21735 #cp_image-4-21735 .cp-rotate-wrap{ transform:rotate( 0deg);}.cp_style_21735 #cp_image-4-21735 .cp-target:hover { }.cp_style_21735 #cp_image-4-21735 .cp-target:hover ~ .cp-field-shadow { }.cp_style_21735 #cp_image-4-21735 { left: 0px;top: 9px;z-index:25;}@media ( max-width: 767px ) {.cp_style_21735 #cp_image-4-21735 .cp-target { width:367px;height:265px;}.cp_style_21735 #cp_image-4-21735 .cp-target:hover { }.cp_style_21735 #cp_image-4-21735 .cp-target { border-style:none;}.cp_style_21735 #cp_image-4-21735 .cp-target ~ .cp-field-shadow { border-style:none;}.cp_style_21735 #cp_image-4-21735 .cp-target { border-color:#757575;}.cp_style_21735 #cp_image-4-21735 .cp-target ~ .cp-field-shadow { border-color:#757575;}.cp_style_21735 #cp_image-4-21735 .cp-target { border-width:1px 1px 1px 1px;}.cp_style_21735 #cp_image-4-21735 .cp-target ~ .cp-field-shadow { border-width:1px 1px 1px 1px;}.cp_style_21735 #cp_image-4-21735 .cp-target { border-radius:0px 0px 0px 0px;}.cp_style_21735 #cp_image-4-21735 .cp-target ~ .cp-field-shadow { border-radius:0px 0px 0px 0px;}.cp_style_21735 #cp_image-4-21735 .cp-target > .cp-close-link { border-radius:0px 0px 0px 0px;}.cp_style_21735 #cp_image-4-21735 .cp-target > .cp-close-image { border-radius:0px 0px 0px 0px;}.cp_style_21735 #cp_image-4-21735 .cp-target { }.cp_style_21735 #cp_image-4-21735 .cp-target ~ .cp-field-shadow { }.cp_style_21735 #cp_image-4-21735 .cp-rotate-wrap{ transform:rotate( 0deg);}.cp_style_21735 #cp_image-4-21735 .cp-target:hover { }.cp_style_21735 #cp_image-4-21735 .cp-target:hover ~ .cp-field-shadow { }.cp_style_21735 #cp_image-4-21735 { left: 0px;top: 9px;z-index:25;}}.cp_style_21735 #cp_heading-4-21735 .cp-target { font-family:Newsreader;font-style:Inherit;font-weight:Inherit;font-size:18px;line-height:1.24;letter-spacing:0px;text-align:center;color:#ffffff;width:377px;height:21px;}.cp_style_21735 #cp_heading-4-21735 .cp-target:hover { }.cp_style_21735 #cp_heading-4-21735 .cp-rotate-wrap{ transform:rotate( 0deg);}.cp_style_21735 #cp_heading-4-21735 { left: 309.5px;top: 137px;z-index:26;}@media ( max-width: 767px ) {.cp_style_21735 #cp_heading-4-21735 .cp-target { font-family:Newsreader;font-style:Inherit;font-weight:Inherit;font-size:23px;line-height:1.08;letter-spacing:0.06;text-align:center;color:#ffffff;width:301px;height:34px;}.cp_style_21735 #cp_heading-4-21735 .cp-target:hover { }.cp_style_21735 #cp_heading-4-21735 .cp-rotate-wrap{ transform:rotate( 0deg);}.cp_style_21735 #cp_heading-4-21735 { left: 317px;top: 81.5px;z-index:26;}}@media ( max-width: 767px ) {.cp_style_21735 .cp-invisible-on-mobile {display: none !important;}}<\/style>\r\n\t\t\t\t\t<div class=\"cp-popup-content cpro-active-step  cp-inline    cp-middle  cp-panel-1\"   data-overlay-click =\"1\" data-title=\"Video ebook banner in-form\" data-module-type=\"inline\"  data-step=\"1\"  data-width=\"700\" data-mobile-width=\"320\" data-height=\"245\" data-mobile-height=\"240\" data-mobile-break-pt=\"767\" data-popup-position=\"middle\" data-mobile-responsive=\"yes\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input type='text' class='cpro-hp-field' name='cpro_hp_feedback_field_21735' value=''>\r\n\t\t\t\t\t\t\t<div class=\"cpro-form-container\">                             \r\n\t\t\t\t\t\t<div id=\"cp_heading-1-21735\" class=\"cp-field-html-data    cp-none cp_has_editor\" data-type=\"cp_heading\"      ><div class=\"cp-rotate-wrap\"><div class=\"cp-target cp-field-element cp-heading tinymce\"  name=\"cp_heading-1\"><p>Crea videos educativos con IA <em>en minutos<\/em><\/p><\/div><\/div>\r\n<\/div><div id=\"cp_heading-3-21735\" class=\"cp-field-html-data    cp-none cp_has_editor\" data-type=\"cp_heading\"      ><div class=\"cp-rotate-wrap\"><div class=\"cp-target cp-field-element cp-heading tinymce\"  name=\"cp_heading-3\"><p><em>LA IA ELIMINA LA BARRERA T&Eacute;CNICA<\/em><\/p><\/div><\/div>\r\n<\/div><div id=\"cp_shape-4-21735\" class=\"cp-field-html-data   cp-shapes-wrap cp-none\" data-type=\"cp_shape\"  data-action=\"none\" data-success-message=\"Thank You for Subscribing!\" data-step=\"\"        data-get-param=\"{{get-param}}\">\r\n\t<div class=\"cp-shape-container\">\r\n\t\t<div class=\"cp-shape-tooltip\"><\/div>\r\n\t\t<label class=\"cp-shape-label\">\r\n\t\t\t\r\n\t\t\t<div class=\"cp-rotate-wrap\"><\/div>\r\n\t\t\t<div class=\"cp-field-shadow\"><\/div>\r\n\t\t<\/label>\r\n\t<\/div>\r\n<\/div><div id=\"cp_button-4-21735\" class=\"cp-field-html-data   cpro_count_conversion cp-none\" data-type=\"cp_button\"   data-action=\"goto_url\" data-step=\"1\"   data-redirect=\"https:\/\/cursoedicionvideos.com\/programas-crear-videos-educativos\/?utm_source=blog&#038;utm_medium=ebook&#038;utm_campaign=Ebook_video\" data-redirect-target=\"_blank\"    >\r\n\t<div class=\"cp-rotate-wrap\"><button type=\"button\" class=\" cp-target cp-field-element cp-button cp-button-field\"  data-success-message=\"Thank You for Subscribing!\" data-get-param=\"false\">Accede a mi gu\u00eda gratuita<\/button>\r\n\t<div class=\"cp-btn-tooltip\"><\/div>\r\n<\/div><\/div><div id=\"cp_shape-6-21735\" class=\"cp-field-html-data   cp-shapes-wrap cp-none\" data-type=\"cp_shape\"  data-action=\"none\" data-success-message=\"Thank You for Subscribing!\" data-step=\"1\"        data-get-param=\"false\">\r\n\t<div class=\"cp-shape-container\">\r\n\t\t<div class=\"cp-shape-tooltip\"><\/div>\r\n\t\t<label class=\"cp-shape-label\">\r\n\t\t\t\r\n\t\t\t<div class=\"cp-rotate-wrap\"><svg xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" fill=\"#cccccc\" class=\"cp-target\" xml:space=\"preserve\" preserveAspectRatio=\"none\">\r\n\t<line x1=\"0\" y1=\"50%\" x2=\"100%\" y2=\"50%\" width=\"100%\" height=\"100%\" style=\"stroke: #cccccc;stroke-width: 2px;\"><\/line>\r\n<\/svg><\/div>\r\n\t\t\t<div class=\"cp-field-shadow\"><\/div>\r\n\t\t<\/label>\r\n\t<\/div>\r\n<\/div><div id=\"cp_image-4-21735\" class=\"cp-field-html-data    cp-none cp-image-ratio\" data-type=\"cp_image\"  data-action=\"none\" data-step=\"1\"     >\r\n\t<div class=\"cp-rotate-wrap\">\r\n\t\t<div class=\"cp-image-main\"><img loading=\"lazy\" decoding=\"async\" width=\"367\" height=\"265\" data-cp-src=\"https:\/\/www.totemguard.com\/aulatotem\/wp-content\/uploads\/2020\/02\/curso-edicion-videos-_opt.png\" class=\"cp-target cp-field-element cp-image cp-img-lazy\" name=\"cp_image-4\" alt=\"ebook-edicion-videos\" src=\"\" loading=\"\">\r\n\t\t\t<div class=\"cp-field-shadow\"><\/div>\r\n\t\t<\/div>\r\n\t\t\r\n\t<\/div>\r\n<\/div><div id=\"cp_heading-4-21735\" class=\"cp-field-html-data    cp-none cp_has_editor\" data-type=\"cp_heading\"      ><div class=\"cp-rotate-wrap\"><div class=\"cp-target cp-field-element cp-heading tinymce\"  name=\"cp_heading-4\"><p>Consejos y herramientas esenciales<\/p><\/div><\/div>\r\n<\/div>\t\t\t\t\t\t\t<\/div>              \r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<\/div><!-- .cp-popup-content -->\r\n\t\t\t\t\t\t      \r\n\t\t<input type=\"hidden\" name=\"param[date]\" value=\"13 May, 2026\" \/>\r\n\t\t<input type=\"hidden\" name=\"action\" value=\"cp_v2_notify_admin\" \/>\r\n\t\t<input type=\"hidden\" name=\"style_id\" value=\"21735\" \/>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div><!-- .cp-popup-wrapper -->\r\n\t\t\t\r\n\t\t\t\t\t<\/div><!-- Modal popup container -->\r\n\t\t\t\n","protected":false},"excerpt":{"rendered":"<p>El peligro de las clases magistrales es que crean la falsa sensaci\u00f3n al profesor de que ense\u00f1a y la falsa sensaci\u00f3n al alumno de que aprende &#8211; Albert Camus Sentarse pasivamente y tomar apuntes no es la mejor manera de aprender. Y sin embargo el 99% de los profesores todav\u00eda siguen este modelo de ense\u00f1ar. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":25035,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[54],"tags":[118,45],"class_list":["post-10254","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-clase-invertida","tag-curso-online","tag-metodologia"],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/www.totemguard.com\/aulatotem\/wp-content\/uploads\/2012\/09\/Eric-mazur-aprendizaje-entre-iguales-scaled.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.totemguard.com\/aulatotem\/wp-json\/wp\/v2\/posts\/10254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.totemguard.com\/aulatotem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.totemguard.com\/aulatotem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.totemguard.com\/aulatotem\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.totemguard.com\/aulatotem\/wp-json\/wp\/v2\/comments?post=10254"}],"version-history":[{"count":210,"href":"https:\/\/www.totemguard.com\/aulatotem\/wp-json\/wp\/v2\/posts\/10254\/revisions"}],"predecessor-version":[{"id":25036,"href":"https:\/\/www.totemguard.com\/aulatotem\/wp-json\/wp\/v2\/posts\/10254\/revisions\/25036"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.totemguard.com\/aulatotem\/wp-json\/wp\/v2\/media\/25035"}],"wp:attachment":[{"href":"https:\/\/www.totemguard.com\/aulatotem\/wp-json\/wp\/v2\/media?parent=10254"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.totemguard.com\/aulatotem\/wp-json\/wp\/v2\/categories?post=10254"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.totemguard.com\/aulatotem\/wp-json\/wp\/v2\/tags?post=10254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}